{"id":10526,"date":"2023-12-27T13:33:32","date_gmt":"2023-12-27T11:33:32","guid":{"rendered":"https:\/\/www.labauma.com\/?page_id=10526"},"modified":"2024-02-13T09:54:39","modified_gmt":"2024-02-13T07:54:39","slug":"rocodromo-en-vilanova","status":"publish","type":"page","link":"https:\/\/www.labauma.com\/es\/rocodromo-en-vilanova\/","title":{"rendered":"Roc\u00f3dromo en Vilanova"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"10526\" class=\"elementor elementor-10526\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-28f06e4 elementor-section-full_width elementor-section-height-default elementor-section-height-default qodef-elementor-content-no\" data-id=\"28f06e4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bd61111\" data-id=\"bd61111\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ca21621 elementor-widget elementor-widget-image\" data-id=\"ca21621\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"2560\" height=\"1707\" src=\"https:\/\/www.labauma.com\/wp-content\/uploads\/2023\/12\/rocodromo-en-vilanova-scaled.jpg\" class=\"attachment-full size-full wp-image-10537\" alt=\"rocodromo en vilanova\" srcset=\"https:\/\/www.labauma.com\/wp-content\/uploads\/2023\/12\/rocodromo-en-vilanova-scaled.jpg 2560w, https:\/\/www.labauma.com\/wp-content\/uploads\/2023\/12\/rocodromo-en-vilanova-300x200.jpg 300w, https:\/\/www.labauma.com\/wp-content\/uploads\/2023\/12\/rocodromo-en-vilanova-1024x683.jpg 1024w, https:\/\/www.labauma.com\/wp-content\/uploads\/2023\/12\/rocodromo-en-vilanova-768x512.jpg 768w, https:\/\/www.labauma.com\/wp-content\/uploads\/2023\/12\/rocodromo-en-vilanova-1536x1024.jpg 1536w, https:\/\/www.labauma.com\/wp-content\/uploads\/2023\/12\/rocodromo-en-vilanova-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1cd4b96 elementor-section-full_width qodef-elementor-content-grid elementor-reverse-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"1cd4b96\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3ef8e6a\" data-id=\"3ef8e6a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fefbcc1 elementor-widget__width-initial elementor-widget elementor-widget-montagne_core_section_title\" data-id=\"fefbcc1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"montagne_core_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m  qodef-section-title qodef-alignment--left \">\n\t\t\t<h1 class=\"qodef-m-title\" >\n\t\t\t\t\tRoc\u00f3dromo en Vilanova\t\t\t<\/h1>\n\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a8c1506 elementor-widget elementor-widget-text-editor\" data-id=\"a8c1506\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">\u00bfSueles escalar en un <\/span><b>roc\u00f3dromo en Vilanova<\/b><span style=\"font-weight: 400;\">? \u00bfTe gustar\u00eda encontrar nuevas v\u00edas y rutas en las que desarrollar tus habilidades y tecnificarte? En <\/span><a href=\"https:\/\/www.labauma.com\/es\/\"><span style=\"font-weight: 400;\">La Bauma<\/span><\/a><span style=\"font-weight: 400;\"> encontrar\u00e1s todo lo que est\u00e1s buscando, y mucho m\u00e1s.<\/span><\/p><p><span style=\"font-weight: 400;\">A tan solo 20 minutos en coche del centro encontrar\u00e1s el mejor roc\u00f3dromo situado en los alrededores del Garraf, un espacio para la pr\u00e1ctica deportiva, que <\/span><b>se ha convertido en un punto de encuentro para una vibrante comunidad de escaladores.<\/b><\/p><p><span style=\"font-weight: 400;\">Desde sus or\u00edgenes hasta la actualidad, este <\/span><b>roc\u00f3dromo en Vilanova i la Geltr\u00fa<\/b><span style=\"font-weight: 400;\"> (a 20 minutos) ha experimentado una transformaci\u00f3n significativa, ampliando sus instalaciones y mejorando continuamente sus servicios para ofrecer a los escaladores una experiencia inigualable.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-40109b1 elementor-section-full_width qodef-elementor-content-grid elementor-section-height-default elementor-section-height-default\" data-id=\"40109b1\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-506861b\" data-id=\"506861b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2c01051 elementor-widget__width-initial elementor-widget elementor-widget-montagne_core_section_title\" data-id=\"2c01051\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"montagne_core_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m  qodef-section-title qodef-alignment--left \">\n\t\t\t<h2 class=\"qodef-m-title\" style=\"color: #FFFFFF\">\n\t\t\t\t\tLas instalaciones: zonas y equipamiento para la escalada en Vilanova\t\t\t<\/h2>\n\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-11d337d elementor-widget elementor-widget-text-editor\" data-id=\"11d337d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Este roc\u00f3dromo en Vilanova i la Geltr\u00fa (a 20 minutos) se destaca por sus <\/span><b>diversas \u00e1reas de escalada<\/b><span style=\"font-weight: 400;\">, que incluyen zonas de boulder y escalada con cuerda. Cada \u00e1rea est\u00e1 equipada con lo \u00faltimo en tecnolog\u00eda de escalada, garantizando una experiencia segura y emocionante.\u00a0<\/span><\/p><p><span style=\"font-weight: 400;\">Incluso contamos con <\/span><b>auto-aseguradores para que puedas disfrutar de tu deporte favorito incluso sin compa\u00f1ero o compa\u00f1era<\/b><span style=\"font-weight: 400;\">. Y es que nuestras <\/span><a href=\"https:\/\/www.labauma.com\/es\/instalaciones\/\"><span style=\"font-weight: 400;\">instalaciones<\/span><\/a><span style=\"font-weight: 400;\"> est\u00e1n equipadas con la \u00faltima tecnolog\u00eda para que cada vez que nos visites puedas enfrentar un reto distinto:\u00a0<\/span><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Route-setting 2 veces a la semana<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">V\u00edas de regletas<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">V\u00edas de compresi\u00f3n de romos<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Lanzamientos<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Bloques coordinativos<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Zona de cuerda<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u00c1rea infantil<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Zona de entrenamiento y tecnificaci\u00f3n<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Moonboard<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Espacio circo<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Bar Camp 4<\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a61c7d2 elementor-section-full_width qodef-elementor-content-grid elementor-section-height-default elementor-section-height-default\" data-id=\"a61c7d2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7e87b66\" data-id=\"7e87b66\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-be2355c elementor-widget__width-initial elementor-widget elementor-widget-montagne_core_section_title\" data-id=\"be2355c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"montagne_core_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m  qodef-section-title qodef-alignment--left \">\n\t\t\t<h2 class=\"qodef-m-title\" >\n\t\t\t\t\tTarifas: escalada en Vilanova flexible\t\t\t<\/h2>\n\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-18febdb elementor-widget elementor-widget-text-editor\" data-id=\"18febdb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Entendemos que cada escalador en nuestro roc\u00f3dromo de Vilanova (a 20 minutos) tiene necesidades diferentes, por lo que ofrecemos una <\/span><b>amplia gama de tarifas.<\/b><span style=\"font-weight: 400;\"> Desde bautizos de escalada para aquellos que deseen probar la experiencia, hasta tarifas de <\/span><a href=\"https:\/\/www.labauma.com\/es\/adultos\/\"><span style=\"font-weight: 400;\">cursos de escalada <\/span><\/a><span style=\"font-weight: 400;\">anuales para los m\u00e1s comprometidos.\u00a0<\/span><\/p><p><b>Y si est\u00e1s empezando a enamorarte de la escalada<\/b><span style=\"font-weight: 400;\">, puedes decidirte por nuestros <\/span><b>cursos de iniciaci\u00f3n<\/b><span style=\"font-weight: 400;\">, con los que aprender\u00e1s los materiales, movimientos, t\u00e9cnicas y consideraciones de seguridad b\u00e1sicas para que puedas crecer en este maravilloso deporte.\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c2fe940 elementor-section-full_width qodef-elementor-content-grid elementor-section-height-default elementor-section-height-default\" data-id=\"c2fe940\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2fbd408\" data-id=\"2fbd408\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0cae727 elementor-widget__width-initial elementor-widget elementor-widget-montagne_core_section_title\" data-id=\"0cae727\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"montagne_core_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m  qodef-section-title qodef-alignment--left \">\n\t\t\t<h2 class=\"qodef-m-title\" >\n\t\t\t\t\tProgramas educativos y de entrenamiento: aprendiendo escalada en Vilanova\t\t\t<\/h2>\n\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c22bfda elementor-widget elementor-widget-text-editor\" data-id=\"c22bfda\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Nuestro compromiso con la formaci\u00f3n de nuevos escaladores se refleja en nuestros programas educativos. <\/span><b>La Escuela Infantil de Escalada <\/b><span style=\"font-weight: 400;\">es el lugar perfecto para que <\/span><b>los m\u00e1s peque\u00f1os comiencen su viaje en este deporte<\/b><span style=\"font-weight: 400;\">, descubre nuestros <\/span><a href=\"https:\/\/www.labauma.com\/es\/infantiles\/\"><span style=\"font-weight: 400;\">roc\u00f3dromos infantiles<\/span><\/a><span style=\"font-weight: 400;\"> y nuestra filosof\u00eda, con la que los m\u00e1s peque\u00f1os conseguir\u00e1n superar todos sus l\u00edmites.\u00a0<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-deb2030 elementor-section-full_width qodef-elementor-content-grid elementor-section-content-top elementor-section-height-default elementor-section-height-default\" data-id=\"deb2030\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d603e4a\" data-id=\"d603e4a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-753060d elementor-widget__width-initial elementor-widget elementor-widget-montagne_core_section_title\" data-id=\"753060d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"montagne_core_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"qodef-shortcode qodef-m  qodef-section-title qodef-alignment--left \">\n\t\t\t<h2 class=\"qodef-m-title\" style=\"color: #FFFFFF\">\n\t\t\t\t\tContacta con nosotros\t\t\t<\/h2>\n\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6e08fac elementor-widget elementor-widget-text-editor\" data-id=\"6e08fac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tSi ten\u00e9is alguna pregunta sobre las actividades que ofrecemos, llenad el formulario de contacto y nos pondremos en contacto con vosotros lo antes posible.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6868a96 elementor-widget-tablet__width-inherit elementor-widget elementor-widget-wp-widget-montagne_core_contact_form_7\" data-id=\"6868a96\" data-element_type=\"widget\" data-e-type=\"widget\" id=\"light-form\" data-widget_type=\"wp-widget-montagne_core_contact_form_7.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div class=\"qodef-contact-form-7\">\n\t\t\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f9469-o1\" lang=\"es-ES\" dir=\"ltr\" data-wpcf7-id=\"9469\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/es\/wp-json\/wp\/v2\/pages\/10526#wpcf7-f9469-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulario de contacto\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"9469\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.6\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"es_ES\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f9469-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7_recaptcha_response\" value=\"\" \/>\n<\/fieldset>\n<label>\r\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"Nombre*\" type=\"text\" name=\"your-name\" \/><\/span> <\/label>\r\n<label>\r\n<span class=\"wpcf7-form-control-wrap\" data-name=\"telefon\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-text wpcf7-validates-as-tel\" aria-invalid=\"false\" placeholder=\"Tel\u00e9fono\" value=\"\" type=\"tel\" name=\"telefon\" \/><\/span><\/label>\r\n<label>\r\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"Email*\" type=\"email\" name=\"your-email\" \/><\/span> <\/label>\r\n<label>\r\n<span class=\"wpcf7-form-control-wrap\" data-name=\"subject\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"Asunto*\" type=\"text\" name=\"subject\" \/><\/span> <\/label>\r\n<label>\r\n    <span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"4\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"your-message\">Mensaje:<\/textarea><\/span> <\/label>\r\n<span class=\"wpcf7-form-control-wrap\" data-name=\"legal\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"legal\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">He le\u00eddo y acepto la <a href=\"\/politica-de-privacitat\/\" target=\"_blank\" style=\"text-decoration: underline;\">pol\u00edtica de privacidad<\/a><\/span><\/label><\/span><\/span><\/span>\r\n<br>\r\n<br>\r\n<button class=\"wpcf7-form-control wpcf7-submit qodef-button qodef-size--normal qodef-layout--filled qodef-m\" type=\"submit\"><span class=\"qodef-m-text\">Enviar<\/span><\/button><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-29cf320 elementor-section-full_width elementor-section-height-default elementor-section-height-default qodef-elementor-content-no\" data-id=\"29cf320\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b7a1348\" data-id=\"b7a1348\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a68e5af elementor-widget__width-inherit elementor-widget elementor-widget-google_maps\" data-id=\"a68e5af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"google_maps.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-custom-embed\">\n\t\t\t<iframe loading=\"lazy\"\n\t\t\t\t\tsrc=\"https:\/\/maps.google.com\/maps?q=La%20Bauma%2C%20Vilafranca%20del%20Pened%C3%A8s&#038;t=m&#038;z=18&#038;output=embed&#038;iwloc=near\"\n\t\t\t\t\ttitle=\"La Bauma, Vilafranca del Pened\u00e8s\"\n\t\t\t\t\taria-label=\"La Bauma, Vilafranca del Pened\u00e8s\"\n\t\t\t><\/iframe>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Roc\u00f3dromo en Vilanova \u00bfSueles escalar en un roc\u00f3dromo en Vilanova? \u00bfTe gustar\u00eda encontrar nuevas v\u00edas y rutas en las que desarrollar tus habilidades y tecnificarte? En La Bauma encontrar\u00e1s todo lo que est\u00e1s buscando, y mucho m\u00e1s. A tan solo 20 minutos en coche del centro encontrar\u00e1s el mejor roc\u00f3dromo situado en los alrededores del [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-full-width.php","meta":{"footnotes":""},"class_list":["post-10526","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Roc\u00f3dromo en Vilanova | La Bauma | 20 minutos en coche<\/title>\n<meta name=\"description\" content=\"Explora con La Bauma el Roc\u00f3dromo de Vilanova. Perfecto para escaladores de todos los niveles. \u00a1Ven y vive la aventura de escalada!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.labauma.com\/es\/rocodromo-en-vilanova\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Roc\u00f3dromo en Vilanova | La Bauma | 20 minutos en coche\" \/>\n<meta property=\"og:description\" content=\"Explora con La Bauma el Roc\u00f3dromo de Vilanova. Perfecto para escaladores de todos los niveles. \u00a1Ven y vive la aventura de escalada!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.labauma.com\/es\/rocodromo-en-vilanova\/\" \/>\n<meta property=\"og:site_name\" content=\"La Bauma\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-13T07:54:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.labauma.com\/wp-content\/uploads\/2023\/12\/rocodromo-en-vilanova-scaled.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.labauma.com\\\/es\\\/rocodromo-en-vilanova\\\/\",\"url\":\"https:\\\/\\\/www.labauma.com\\\/es\\\/rocodromo-en-vilanova\\\/\",\"name\":\"Roc\u00f3dromo en Vilanova | La Bauma | 20 minutos en coche\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.labauma.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.labauma.com\\\/es\\\/rocodromo-en-vilanova\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.labauma.com\\\/es\\\/rocodromo-en-vilanova\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.labauma.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/rocodromo-en-vilanova-scaled.jpg\",\"datePublished\":\"2023-12-27T11:33:32+00:00\",\"dateModified\":\"2024-02-13T07:54:39+00:00\",\"description\":\"Explora con La Bauma el Roc\u00f3dromo de Vilanova. Perfecto para escaladores de todos los niveles. \u00a1Ven y vive la aventura de escalada!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.labauma.com\\\/es\\\/rocodromo-en-vilanova\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.labauma.com\\\/es\\\/rocodromo-en-vilanova\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.labauma.com\\\/es\\\/rocodromo-en-vilanova\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.labauma.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/rocodromo-en-vilanova-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.labauma.com\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/rocodromo-en-vilanova-scaled.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.labauma.com\\\/es\\\/rocodromo-en-vilanova\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/www.labauma.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Roc\u00f3dromo en Vilanova\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.labauma.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.labauma.com\\\/es\\\/\",\"name\":\"La Bauma\",\"description\":\"Escola d&#039;escalada\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.labauma.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Roc\u00f3dromo en Vilanova | La Bauma | 20 minutos en coche","description":"Explora con La Bauma el Roc\u00f3dromo de Vilanova. Perfecto para escaladores de todos los niveles. \u00a1Ven y vive la aventura de escalada!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.labauma.com\/es\/rocodromo-en-vilanova\/","og_locale":"es_ES","og_type":"article","og_title":"Roc\u00f3dromo en Vilanova | La Bauma | 20 minutos en coche","og_description":"Explora con La Bauma el Roc\u00f3dromo de Vilanova. Perfecto para escaladores de todos los niveles. \u00a1Ven y vive la aventura de escalada!","og_url":"https:\/\/www.labauma.com\/es\/rocodromo-en-vilanova\/","og_site_name":"La Bauma","article_modified_time":"2024-02-13T07:54:39+00:00","og_image":[{"url":"https:\/\/www.labauma.com\/wp-content\/uploads\/2023\/12\/rocodromo-en-vilanova-scaled.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.labauma.com\/es\/rocodromo-en-vilanova\/","url":"https:\/\/www.labauma.com\/es\/rocodromo-en-vilanova\/","name":"Roc\u00f3dromo en Vilanova | La Bauma | 20 minutos en coche","isPartOf":{"@id":"https:\/\/www.labauma.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.labauma.com\/es\/rocodromo-en-vilanova\/#primaryimage"},"image":{"@id":"https:\/\/www.labauma.com\/es\/rocodromo-en-vilanova\/#primaryimage"},"thumbnailUrl":"https:\/\/www.labauma.com\/wp-content\/uploads\/2023\/12\/rocodromo-en-vilanova-scaled.jpg","datePublished":"2023-12-27T11:33:32+00:00","dateModified":"2024-02-13T07:54:39+00:00","description":"Explora con La Bauma el Roc\u00f3dromo de Vilanova. Perfecto para escaladores de todos los niveles. \u00a1Ven y vive la aventura de escalada!","breadcrumb":{"@id":"https:\/\/www.labauma.com\/es\/rocodromo-en-vilanova\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.labauma.com\/es\/rocodromo-en-vilanova\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.labauma.com\/es\/rocodromo-en-vilanova\/#primaryimage","url":"https:\/\/www.labauma.com\/wp-content\/uploads\/2023\/12\/rocodromo-en-vilanova-scaled.jpg","contentUrl":"https:\/\/www.labauma.com\/wp-content\/uploads\/2023\/12\/rocodromo-en-vilanova-scaled.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.labauma.com\/es\/rocodromo-en-vilanova\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.labauma.com\/es\/"},{"@type":"ListItem","position":2,"name":"Roc\u00f3dromo en Vilanova"}]},{"@type":"WebSite","@id":"https:\/\/www.labauma.com\/es\/#website","url":"https:\/\/www.labauma.com\/es\/","name":"La Bauma","description":"Escola d&#039;escalada","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.labauma.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/www.labauma.com\/es\/wp-json\/wp\/v2\/pages\/10526","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.labauma.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.labauma.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.labauma.com\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.labauma.com\/es\/wp-json\/wp\/v2\/comments?post=10526"}],"version-history":[{"count":22,"href":"https:\/\/www.labauma.com\/es\/wp-json\/wp\/v2\/pages\/10526\/revisions"}],"predecessor-version":[{"id":10624,"href":"https:\/\/www.labauma.com\/es\/wp-json\/wp\/v2\/pages\/10526\/revisions\/10624"}],"wp:attachment":[{"href":"https:\/\/www.labauma.com\/es\/wp-json\/wp\/v2\/media?parent=10526"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}